{"id":15560,"date":"2024-11-06T08:30:18","date_gmt":"2024-11-06T08:30:18","guid":{"rendered":"http:\/\/155.253.13.43\/personale\/ferrarini-giovanni\/"},"modified":"2026-02-23T10:58:06","modified_gmt":"2026-02-23T10:58:06","slug":"ferrarini-giovanni","status":"publish","type":"personale","link":"https:\/\/test.itc.cnr.it\/wordpress\/personale\/ferrarini-giovanni\/","title":{"rendered":"FERRARINI GIOVANNI"},"content":{"rendered":"<p>Ricercatore<\/p>\n<p>Sede: Padova<\/p>\n<p>Giovanni Ferrarini \u00e8 ricercatore e responsabile del laboratorio di termografia del CNR-ITC di Padova. La sua attivit\u00e0 di ricerca riguarda le applicazioni della termografia infrarossa per l\u2019energetica degli edifici, i test non distruttivi, la caratterizzazione termica dei materiali e i sistemi di climatizzazione. Ha svolto attivit\u00e0 di ricerca come assegnista al CNR-ITC e presso l\u2019Universit\u00e9 Laval (Qu\u00e9bec). Ha conseguito il dottorato in ingegneria industriale all\u2019Universit\u00e0 di Padova. Ha partecipato a progetti di ricerca nazionali (PRIN, PNRR) ed europei (FP7, H2020, COSME, HE) su efficienza energetica, accumulo termico e sistemi radianti, conducendo numerose indagini su edifici storici in Italia e all\u2019estero. \u00c8 coautore di un brevetto e autore di oltre 70 pubblicazioni scientifiche. \u00c8 revisore per riviste internazionali, membro di comitati scientifici di conferenze (Thermosense, AITA, QIRT) e vincitore di premi (AITA 2015, Thermosense 2016).<br \/>\nhttps:\/\/orcid.org\/0000-0001-7149-0578<br \/>\nhttps:\/\/iris.cnr.it\/cris\/rp\/rp02805<\/p>\n","protected":false},"featured_media":111,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":""},"class_list":["post-15560","personale","type-personale","status-publish","has-post-thumbnail","hentry"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini.jpg",1411,2106,false],"thumbnail":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini-150x150.jpg",150,150,true],"medium":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini-201x300.jpg",201,300,true],"medium_large":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini-768x1146.jpg",768,1146,true],"large":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini-686x1024.jpg",322,480,true],"1536x1536":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini-1029x1536.jpg",1029,1536,true],"2048x2048":["https:\/\/test.itc.cnr.it\/wordpress\/wp-content\/uploads\/2024\/10\/Ferrarini-1372x2048.jpg",1372,2048,true]},"uagb_author_info":{"display_name":"webm","author_link":"https:\/\/test.itc.cnr.it\/wordpress\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Ricercatore Sede: Padova Giovanni Ferrarini \u00e8 ricercatore e responsabile del laboratorio di termografia del CNR-ITC di Padova. La sua attivit\u00e0 di ricerca riguarda le applicazioni della termografia infrarossa per l\u2019energetica degli edifici, i test non distruttivi, la caratterizzazione termica dei materiali e i sistemi di climatizzazione. Ha svolto attivit\u00e0 di ricerca come assegnista al CNR-ITC&hellip;","_links":{"self":[{"href":"https:\/\/test.itc.cnr.it\/wordpress\/wp-json\/wp\/v2\/personale\/15560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.itc.cnr.it\/wordpress\/wp-json\/wp\/v2\/personale"}],"about":[{"href":"https:\/\/test.itc.cnr.it\/wordpress\/wp-json\/wp\/v2\/types\/personale"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.itc.cnr.it\/wordpress\/wp-json\/wp\/v2\/media\/111"}],"wp:attachment":[{"href":"https:\/\/test.itc.cnr.it\/wordpress\/wp-json\/wp\/v2\/media?parent=15560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}